{"id":26357,"date":"2021-09-23T16:09:27","date_gmt":"2021-09-23T16:09:27","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=26357"},"modified":"2021-09-23T16:09:27","modified_gmt":"2021-09-23T16:09:27","slug":"parte-area-sanremo-2021-da-oggi-sono-aperte-le-iscrizioni-lunico-concorso-che-fa-accedere-4-artisti-emergenti-alla-serata-finale-di-sanremo-giovani","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2021\/09\/23\/parte-area-sanremo-2021-da-oggi-sono-aperte-le-iscrizioni-lunico-concorso-che-fa-accedere-4-artisti-emergenti-alla-serata-finale-di-sanremo-giovani\/","title":{"rendered":"Parte AREA SANREMO 2021 (da oggi sono aperte le iscrizioni), l&#8217;unico concorso che fa accedere 4 artisti emergenti alla serata finale di SANREMO GIOVANI!"},"content":{"rendered":"<p>DA OGGI SONO APERTE LE ISCRIZIONI AD AREA SANREMO 2021<br \/>\nMANIFESTAZIONE GESTITA E ORGANIZZATA DALLA<br \/>\nFONDAZIONE ORCHESTRA SINFONICA DI SANREMO<\/p>\n<p>L\u2019UNICO CONCORSO CHE FA ACCEDERE 4 ARTISTI EMERGENTI<br \/>\nALLA SERATA FINALE DI \u201cSANREMO GIOVANI\u201d<\/p>\n<p>DIREZIONE ARTISTICA<br \/>\nMASSIMO COTTO<\/p>\n<p>COMMISSIONE DI VALUTAZIONE<br \/>\nPIERO PEL\u00d9, MAURO ERMANNO GIOVANARDI e MARTA TRIPODI<br \/>\nPresidenti di Commissione FRANCO ZANETTI e il Maestro GIUSEPPE VESSICCHIO<br \/>\nCommissario supplente MAURILIO GIORDANA<\/p>\n<p>Presidente Onorario VITTORIO DE SCALZI<\/p>\n<p>Da oggi, gioved\u00ec 23 settembre, sono aperte le iscrizioni all\u2019edizione 2021 di AREA SANREMO, l\u2019unico concorso che d\u00e0 la possibilit\u00e0 a 4 artisti emergenti di poter accedere alla serata finale di \u201cSANREMO GIOVANI\u201d, prevista il 15 dicembre in diretta su Rai1, in prima serata, dal Teatro del Casin\u00f2 di Sanremo.<\/p>\n<p>AREA SANREMO \u00e8 una manifestazione organizzata e gestita dalla Fondazione Orchestra Sinfonica di Sanremo, presieduta dall\u2019Avv. Filippo Biol\u00e8, dedicata ai giovani artisti di et\u00e0 compresa tra i 16 anni compiuti e i 30 non ancora compiuti al 1\u00b0 gennaio 2022 (singolo, duo o gruppo). La Direzione Artistica di Area Sanremo sar\u00e0 a cura di Massimo Cotto.<\/p>\n<p>Per iscriversi \u00e8 necessario scaricare il bando ufficiale dal sito www.area-sanremo.it, compilare la domanda di iscrizione online e inviare il materiale richiesto entro e non oltre il 21 ottobre.<\/p>\n<p>I 2 brani presentati, uno destinato alle audizioni e l\u2019altro per l\u2019eventuale partecipazione al Festival di Sanremo 2022, dovranno essere inediti, in lingua italiana e della durata di 3 minuti e 30 secondi.<\/p>\n<p>Le canzoni saranno selezionate dalla Commissione di Valutazione composta da Franco Zanetti (Presidente), Mauro Ermanno Giovanardi e Marta Tripodi. Al termine della prima fase eliminatoria, si aggiungeranno alla Commissione il Maestro Giuseppe Vessicchio (in qualit\u00e0 di Presidente) e Piero Pel\u00f9. Il commissario supplente sar\u00e0 Maurilio Giordana. Il Presidente Onorario della Commissione di Valutazione sar\u00e0 Vittorio De Scalzi.<\/p>\n<p>I vincitori di AREA SANREMO saranno proclamati dalla Commissione di Valutazione e avranno la possibilit\u00e0 di sostenere un\u2019audizione davanti alla Commissione Artistica della RAI, che decreter\u00e0 i 4 artisti che parteciperanno alla serata finale di Sanremo Giovani.<\/p>\n<p>Grazie alla collaborazione con KNTNR, startup che si occupa di sostenere nuovi talenti in campo artistico, verranno offerte ai partecipanti al concorso fino a 10 borse di studio dal valore di 2500 euro ciascuna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DA OGGI SONO APERTE LE ISCRIZIONI AD AREA SANREMO 2021 MANIFESTAZIONE GESTITA E ORGANIZZATA DALLA FONDAZIONE ORCHESTRA SINFONICA DI SANREMO L\u2019UNICO CONCORSO CHE FA ACCEDERE 4 ARTISTI EMERGENTI ALLA SERATA<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2021\/09\/23\/parte-area-sanremo-2021-da-oggi-sono-aperte-le-iscrizioni-lunico-concorso-che-fa-accedere-4-artisti-emergenti-alla-serata-finale-di-sanremo-giovani\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":26366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/26357"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=26357"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/26357\/revisions"}],"predecessor-version":[{"id":26367,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/26357\/revisions\/26367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/26366"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=26357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=26357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=26357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}