{"id":28329,"date":"2021-11-26T11:48:02","date_gmt":"2021-11-26T11:48:02","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=28329"},"modified":"2021-11-26T11:48:02","modified_gmt":"2021-11-26T11:48:02","slug":"fellow-non-farmi-andare","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2021\/11\/26\/fellow-non-farmi-andare\/","title":{"rendered":"FELLOW &#8211; Non farmi andare"},"content":{"rendered":"<div><strong>Da venerd\u00ec 26 novembre \u00e8 in radio e su tutte le piattaforme digitali\u00a0<em>\u201cNon farmi andare\u201d<\/em>, il nuovo singolo di FELLOW<\/strong>, prodotto da Michele Canova Iorfida e Jaime Estalella e contenuto nell\u2019album\u00a0<strong><em>\u201cX FACTOR MIXTAPE VOL. 2\u201d<\/em>\u00a0<\/strong>disponibile su tutti i digital partner.<\/div>\n<div><\/div>\n<div>\u201c<strong><em>Non Farmi Andare<\/em><\/strong>\u201d \u00e8 una canzone che parla di quel nodo che ti prende alla gola quando capisci che il tempo lentamente prende le cose e le persone importanti, in cambio di ricordi, che spesso lasciano un vuoto. Un giorno ti svegli e ti chiedi come il passato, seppur a volte molto breve, possa sembrare cos\u00ec lontano da dare quasi l\u2019impressione di star vivendo una seconda vita, ti chiedi dove siano finite quelle persone importanti, che cosa stiano facendo in questo momento, realizzi che non sono pi\u00f9 parte del tuo percorso, e pensare ai ricordi felici ti lascia una sensazione di dolce malinconia. Avresti voluto che le cose fossero andate diversamente, perch\u00e9 non \u00e8 stato facile ricominciare senza di loro e pronunciare il loro nome \u00e8 ancora difficile, fa ancora male, soprattutto quando avresti fatto qualsiasi cosa per non perderle.<\/div>\n<div><u>\u00a0<\/u><\/div>\n<div>L\u2019appuntamento con\u00a0<strong>X Factor 2021 &#8211; I Live<\/strong>\u00a0\u00e8 tutti i gioved\u00ec alle 21.15 su Sky Uno, sempre disponibile on demand, visibile su Sky Go e in streaming su NOW.<\/div>\n<div><\/div>\n<div>Da venerd\u00ec 26 novembre l\u2019<strong><em>X FACTOR MIXTAPE VOL. 2<\/em><\/strong>\u00a0(Sony Music Italy) si arricchisce di 7 nuove imperdibili tracce che i concorrenti hanno presentato sul palco dei Live durante la puntata del 25 novembre.<\/div>\n<div><u>\u00a0<\/u><\/div>\n<div><u>Biografia<\/u><\/div>\n<div>Federico Castello ha 21 anni, \u00e8 nato ad Asti e vive a Torino. Aggiungendo la \u201cw\u201d a una parte del suo nome, si costruisce la parola \u201c<strong>FELLOW<\/strong>\u201d che in inglese significa \u201ccompagno di vita\u201d. Ha iniziato a fare musica quando aveva 8 anni insieme a suo nonno alle sagre del suo paese, cantando cover di brani anni \u201860 &#8211; \u201870. \u00c8 da quel momento che<strong>\u00a0FELLOW<\/strong>\u00a0scopre la sua passione per la musica, e il palco diventa il posto che gli trasmette pi\u00f9 emozioni e dove si sente veramente s\u00e9 stesso. Alle\u00a0<strong>Audizioni<\/strong>\u00a0si \u00e8 presentato ai giudici di X Factor 2021 con grande dolcezza ed umilt\u00e0, e quando ha cantato e suonato al pianoforte una cover di\u00a0<strong><em>\u201cFollow you\u201d<\/em><\/strong>\u00a0degli Imagine Dragons ha rivelato un timbro di voce cos\u00ec emozionante da far venire la pelle d\u2019oca. Ai\u00a0<strong>Bootcamp<\/strong>,\u00a0<strong>FELLOW<\/strong>\u00a0si \u00e8 esibito davanti a Mika con una cover di\u00a0<strong><em>\u201cTill Forever Falls Apart\u201d<\/em><\/strong>\u00a0di Ashe &amp; FINNEAS, lasciando tutti di nuovo senza parole. Il cantante supera anche l\u2019ultima, decisiva, fase di selezione, gli\u00a0<strong>Home Visit<\/strong>, con una cover di\u00a0<strong><em>\u201cLondon\u201d<\/em><\/strong>\u00a0di Benjamin Clementine e\u00a0<strong>Mika<\/strong>\u00a0lo sceglie per il suo<strong>\u00a0Roster.\u00a0<\/strong>Debutta ai\u00a0<strong>Live\u00a0<\/strong>con un brano originale, la ballad\u00a0<strong><em>\u201cFire\u201d<\/em><\/strong>: poco pi\u00f9 di tre minuti per entrare in punta di piedi nell\u2019intimit\u00e0 dell\u2019ascoltatore e poi esplodere in un climax di rabbia e dolore.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Da venerd\u00ec 26 novembre \u00e8 in radio e su tutte le piattaforme digitali\u00a0\u201cNon farmi andare\u201d, il nuovo singolo di FELLOW, prodotto da Michele Canova Iorfida e Jaime Estalella e contenuto<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2021\/11\/26\/fellow-non-farmi-andare\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":28330,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28329"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=28329"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28329\/revisions"}],"predecessor-version":[{"id":28331,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28329\/revisions\/28331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/28330"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=28329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=28329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=28329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}