{"id":28444,"date":"2021-11-29T17:40:53","date_gmt":"2021-11-29T17:40:53","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=28444"},"modified":"2021-11-29T17:40:53","modified_gmt":"2021-11-29T17:40:53","slug":"cristina-dona-esce-il-3-dicembre-desidera-il-nuovo-album-di-inediti","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2021\/11\/29\/cristina-dona-esce-il-3-dicembre-desidera-il-nuovo-album-di-inediti\/","title":{"rendered":"CRISTINA DON\u00c0 &#8211; ESCE IL 3 DICEMBRE &#8220;deSidera&#8221; IL NUOVO ALBUM DI INEDITI."},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>\u201cdeSidera\u201d<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00c8 IL NUOVO ALBUM DI INEDITI DI<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>CRISTINA DON\u00c0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>IN USCITA IL 3 DICEMBRE<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">(Fenix Music \/ The Orchard)<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">In formato CD e Vinile<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">A distanza di sette anni dall\u2019ultimo disco di inediti, CRISTINA DON\u00c0 pubblica il nuovo album \u201cdeSidera\u201d, in uscita il 3 dicembre.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Anticipato dai primi estratti \u201cDesiderio\u201d e \u201cColpa\u201d, \u201cdeSidera\u201d segna il ritorno di una tra le cantautrici pi\u00f9 stimate del panorama musicale italiano, punto di riferimento e figura ispiratrice per le nuove generazioni di musicisti.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Link al videoclip ufficiale di \u201cDesiderio (Cannibal Version)\u201d:<\/strong>\u00a0<a href=\"https:\/\/youtu.be\/HN8QKoljk-4\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/youtu.be\/HN8QKoljk-4&amp;source=gmail&amp;ust=1638274081931000&amp;usg=AOvVaw2kQ6MVsiX9VW0-KfLxiNkR\">https:\/\/youtu.be\/HN8QKoljk-4<\/a><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Link al videoclip ufficiale di \u201cColpa\u201d su YouTube<\/strong>:\u00a0<a href=\"https:\/\/youtu.be\/B3TqZ6Wboi8\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/youtu.be\/B3TqZ6Wboi8&amp;source=gmail&amp;ust=1638274081931000&amp;usg=AOvVaw3ahhJxV12Ht8UPgbfRcsfj\">https:\/\/youtu.be\/B3TqZ6Wboi8<\/a><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">L\u2019artista, che ha presentato dal vivo alcuni estratti dal nuovo disco durante la lunga tourn\u00e9e estiva che l\u2019ha vista calcare i palchi dei pi\u00f9 importanti festival nazionali e delle principali rassegne, \u00e8 attualmente in tour con le prime date indoor in programma nei teatri italiani. Questi i prossimi appuntamenti in calendario:<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">27 Novembre 2021 &#8211; Mercato Saraceno (FC) &#8211; Teatro di Palazzo Dolcini<\/p>\n<p style=\"font-weight: 400;\">12 Dicembre 2021 &#8211; Gioia del Colle (BA)\u00a0\u2013 Teatro Comunale Rossini<\/p>\n<p style=\"font-weight: 400;\">13 Gennaio 2022 \u2013 Maranello (MO) &#8211; Auditorium Enzo Ferrari<\/p>\n<p style=\"font-weight: 400;\">28 Gennaio 2022 &#8211; Settimo Torinese &#8211; Suoneria Club<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>\u201cdeSidera\u201d \u2013 IL DISCO<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>\u00a0<\/em><\/p>\n<p style=\"font-weight: 400;\">L\u2019atteso lavoro discografico, che vede la luce dopo una fortunata campagna crowdfunding, gravita intorno al tema del \u201cdesiderio\u201d, che cuce i brani con un sottile filo rosso. Il desiderio come motore indispensabile delle nostre vite, ma anche fonte di un incolmabile vuoto, di un\u2019insoddisfazione perenne che porta con s\u00e9 le sue conseguenze. Il titolo stesso indica liberamente l\u2019etimologia della parola desiderio, letteralmente \u201cmancanza di stelle\u201d.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\u201cdeSidera\u201d si presenta come un album aspro e multiforme, dai tratti marcati, dalle pennellate forti, stratificato e certamente identitario, frutto di un lavoro meditato e accorto. Le parti musicali sono scritte, ancora una volta, a quattro mani col musicista e produttore Saverio Lanza, che ha curato anche gli arrangiamenti del disco. Ne scaturisce una produzione atipica e, per la prima volta nei lavori di Cristina, compaiono echi di \u201celettronica preistorica\u201d, cos\u00ec definibili per la loro natura primitiva, scarna e minimale.<\/p>\n<p style=\"font-weight: 400;\">Dieci canzoni che nascono da un\u2019autoanalisi attraverso la quale si tenta di indagare, alla luce del desiderio, l\u2019attuale condizione umana come riflesso di una somma di scelte e comportamenti individuali. Un punto di vista che scopre verit\u00e0 dai lineamenti duri e crudi, scava in profondit\u00e0 e scuote, ma prova anche ad immaginare orizzonti possibili. Si scoprono fragilit\u00e0 e debolezze della nostra umanit\u00e0 al cospetto di ci\u00f2 che siamo oggi e del pianeta che ci ospita. Ed \u00e8 proprio davanti ad una realt\u00e0 apparentemente incontrovertibile che nasce la necessit\u00e0 di una presa di coscienza prima di tutto personale, che ne auspica una collettiva poi.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">I brani che compongono l\u2019album, scritti interamente prima della pandemia, fatta eccezione per \u201cSenza fucile n\u00e9 spada\u201d, raccontano di un tentativo che invita alla riflessione e a una nuova consapevolezza, per ripartire ad occhi ben aperti.<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>TRACKLIST \u201cdeSidera\u201d<\/strong><\/p>\n<p style=\"font-weight: 400;\">01_Distratti<\/p>\n<p style=\"font-weight: 400;\">02_Colpa<\/p>\n<p style=\"font-weight: 400;\">03_Conto alla rovescia<\/p>\n<p style=\"font-weight: 400;\">04_Desiderio<\/p>\n<p style=\"font-weight: 400;\">05_Come quando gli alberi si parlano<\/p>\n<p style=\"font-weight: 400;\">06_Torna<\/p>\n<p style=\"font-weight: 400;\">07_Senza fucile n\u00e9 spada<\/p>\n<p style=\"font-weight: 400;\">08_Oltre<\/p>\n<p style=\"font-weight: 400;\">09_L\u2019autunno<\/p>\n<p style=\"font-weight: 400;\">10_Titoli di coda<\/p>\n<p style=\"font-weight: 400;\"><strong><em>\u00a0<\/em><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>CREDITI ALBUM \u201cdeSidera\u201d<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">Testi: Cristina Don\u00e0<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Musica: Cristina Don\u00e0 e Saverio Lanza<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Cristina Don\u00e0: parole cantate, cori, chitarre elettroniche, alterazioni paesaggistiche<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Saverio Lanza: chitarre varie, piano, basso, tromba, cori e saette, viola, elettronica preistorica<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Cristiano Calcagnile: batteria, percussioni, bagliori di suoni su \u201cConto alla rovescia\u201d, \u201cCome quando gli alberi si parlano\u201d, \u201cL\u2019autunno\u201d<\/p>\n<p style=\"font-weight: 400;\">Fabrizio Morganti: batterie ostinate e disperse su \u201cDesiderio\u201d, \u201cTorna\u201d, \u201cSenza fucile n\u00e9 spada\u201d, \u201cOltre\u201d, \u201cTitoli di coda\u201d<\/p>\n<p style=\"font-weight: 400;\">Leonardo Ristori: violoncello su \u201cTorna\u201d e \u201cL\u2019autunno\u201d<\/p>\n<p style=\"font-weight: 400;\">Simone Santini: sax, flauti, oboe su \u201cConto alla rovescia\u201d e \u201cCome quando gli alberi si parlano\u201d<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Prodotto, arrangiato e registrato da Saverio Lanza in molti luoghi tra i quali: casa Don\u00e0, casa Lanza, casa-studio Calcagnile, casa-studio Morganti, Parsifal Recording Studio<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Mixato da Francesco Felcini al Parsifal Recording Studio di Sesto Fiorentino (FI)<\/p>\n<p style=\"font-weight: 400;\">Masterizzato da Claudio Giussani presso Energy Mastering Studio di Milano<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Art direction e artwork: Federica Fabbri<\/p>\n<p style=\"font-weight: 400;\">Graphic design: Cesare Camardo<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><a href=\"http:\/\/www.cristinadona.it\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.cristinadona.it\/&amp;source=gmail&amp;ust=1638274081931000&amp;usg=AOvVaw0xc5n-2ncRAo2ldkvTdBTv\">www.cristinadona.it<\/a>\u00a0&#8211;\u00a0<a href=\"http:\/\/www.facebook.com\/cristinadona\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.facebook.com\/cristinadona&amp;source=gmail&amp;ust=1638274081931000&amp;usg=AOvVaw0-k4Oye0iBL26cvbrROnEg\">www.facebook.com\/cristinadona<\/a><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Ufficio stampa e promozione per Cristina Don\u00e0<\/strong>:<\/p>\n<p style=\"font-weight: 400;\">BIG TIME &#8211;\u00a0<a href=\"mailto:pressoff@bigtimeweb.it\">pressoff@bigtimeweb.it<\/a>\u00a0 &#8211; Claudia Felici \/ Fabio Tiriemmi \/ Gertrude Cesti\u00e8<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Label:<\/strong><\/p>\n<p style=\"font-weight: 400;\">FENIX MUSIC &#8211;\u00a0<a href=\"mailto:marta.scandorza@fenixent.com\">marta.scandorza@fenixent.com<\/a><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Booking &#8211; info concerti<\/strong>:<\/p>\n<p style=\"font-weight: 400;\">PONDEROSA MUSIC &amp; ART &#8211; Giuseppe Ponti &#8211;\u00a0<a href=\"mailto:giuseppe@ponderosa.it\">giuseppe@ponderosa.it<\/a><\/p>\n<p style=\"font-weight: 400;\">Responsabile comunicazione per PONDEROSA MUSIC &amp; ART &#8211; Sara Mehrjoei &#8211;\u00a0<a href=\"mailto:sara@ponderosa.it\">sara@ponderosa.it<\/a><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Management<\/strong>:<\/p>\n<p style=\"font-weight: 400;\">GIANNI CICCHI &#8211;\u00a0<a href=\"mailto:gianni.cicchi@gmail.com\">gianni.cicchi@gmail.com<\/a><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Foto<\/strong>:<\/p>\n<p style=\"font-weight: 400;\">FRANCESCA SARA CAULI &#8211;\u00a0<a href=\"http:\/\/www.francescasaracauli.com\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.francescasaracauli.com\/&amp;source=gmail&amp;ust=1638274081931000&amp;usg=AOvVaw000xDG45jxJj17CFZkqEDv\">www.francescasaracauli.com<\/a><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Discografia completa Cristina Don\u00e0:<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><u>Album<\/u><\/p>\n<p style=\"font-weight: 400;\">1997\u00a0<strong>Tregua<\/strong>\u00a0&#8211; Mescal<\/p>\n<p style=\"font-weight: 400;\">1999\u00a0<strong>Nido<\/strong>\u00a0&#8211; Mescal<\/p>\n<p style=\"font-weight: 400;\">2003\u00a0<strong>Dove sei tu<\/strong>\u00a0&#8211; Mescal<\/p>\n<p style=\"font-weight: 400;\">2004 Cristina Don\u00e0 &#8211; Mescal\/Rykodisc<\/p>\n<p style=\"font-weight: 400;\">2007\u00a0<strong>La quinta stagione<\/strong>\u00a0\u2013 EMI<\/p>\n<p style=\"font-weight: 400;\">2008 Piccola faccia \u2013 EMI<\/p>\n<p style=\"font-weight: 400;\">2011\u00a0<strong>Torno a casa a piedi<\/strong>\u00a0&#8211; EMI<\/p>\n<p style=\"font-weight: 400;\">2014\u00a0<strong>Cos\u00ec vicini<\/strong>\u00a0&#8211; QBL\/Believe Rec.<\/p>\n<p style=\"font-weight: 400;\">2017 AA.VV Tregua 1997\/2017 Stelle Buone &#8211; Believe Rec.<\/p>\n<p style=\"font-weight: 400;\">2019 Cristina Don\u00e0 e Ginevra Di Marco &#8211; D&amp;D\/Funambulo<\/p>\n<p style=\"font-weight: 400;\">2021\u00a0<strong>deSidera\u00a0<\/strong>\u2013 Fenix Music<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><u>EP<\/u><\/p>\n<p style=\"font-weight: 400;\">2000 Goccia &#8211; Mescal<\/p>\n<p style=\"font-weight: 400;\">2003 Nel mio giardino &#8211; Mescal<\/p>\n<p style=\"font-weight: 400;\">2003 Triathlon &#8211; Mescal<\/p>\n<p style=\"font-weight: 400;\">2003 Invisibile &#8211; Mescal<\/p>\n<p style=\"font-weight: 400;\">2004 Invisibile Girl &#8211; Mescal<\/p>\n<p style=\"font-weight: 400;\">2005 Triathlon \u201cUk version\u201d \u2013 Mescal<\/p>\n<p style=\"font-weight: 400;\">2021 Settembre\/Universo (Theatre Version) &#8211; (vinile7\u201d) &#8211; Fenix Music<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cdeSidera\u201d \u00a0 \u00c8 IL NUOVO ALBUM DI INEDITI DI \u00a0 CRISTINA DON\u00c0 \u00a0 IN USCITA IL 3 DICEMBRE \u00a0 (Fenix Music \/ The Orchard) In formato CD e Vinile A<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2021\/11\/29\/cristina-dona-esce-il-3-dicembre-desidera-il-nuovo-album-di-inediti\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":28445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28444"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=28444"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28444\/revisions"}],"predecessor-version":[{"id":28446,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28444\/revisions\/28446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/28445"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=28444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=28444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=28444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}