{"id":28450,"date":"2021-11-29T18:51:27","date_gmt":"2021-11-29T18:51:27","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=28450"},"modified":"2021-11-29T18:51:27","modified_gmt":"2021-11-29T18:51:27","slug":"bryan-adams-e-in-pre-order-il-nuovo-album-so-happy-it-hurts-bmg-che-esce-l11-marzo-2022-a-febbraio-2022-tre-date-in-italia","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2021\/11\/29\/bryan-adams-e-in-pre-order-il-nuovo-album-so-happy-it-hurts-bmg-che-esce-l11-marzo-2022-a-febbraio-2022-tre-date-in-italia\/","title":{"rendered":"BRYAN ADAMS: \u00e8 in pre-order il nuovo album \u201cSo Happy It Hurts\u201d (BMG) che esce l\u201911 marzo 2022, a febbraio 2022 tre date in Italia!"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>BRYAN ADAMS<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>L\u201911 MARZO 2022 ESCE IL NUOVO ALBUM<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><em>\u201cSO HAPPY IT HURTS\u201d<\/em><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>L\u2019album \u00e8 ora in pre-order<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><a href=\"https:\/\/bryanadams.lnk.to\/SoHappyItHurtsAlbum\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/bryanadams.lnk.to\/SoHappyItHurtsAlbum&amp;source=gmail&amp;ust=1638274084530000&amp;usg=AOvVaw1WTnxRsbKmmN_BfJ3A1n_I\">https:\/\/bryanadams.lnk.to\/SoHappyItHurtsAlbum<\/a><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>A febbraio IN CONCERTO a ROMA, FIRENZE e CONEGLIANO (TV)<\/strong><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">40 anni di carriera, 14 album che sono impressi nella memoria di pi\u00f9 generazioni, prima posizione in classifica in 40 Paesi nel mondo, e poi ancora 3 Academy Award nomination, 5 Golden Globe nomination, 1 Grammy Award:\u00a0<strong>il rocker canadese BRYAN ADAMS<\/strong>\u00a0<strong>torna<\/strong>\u00a0<strong>con il nuovo album\u00a0<em>\u201cSo Happy It Hurts\u201d<\/em><\/strong>\u00a0(BMG)\u00a0<strong>che<\/strong>\u00a0<strong>uscir\u00e0 l\u201911 marzo 2022!<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><em>\u201cSo Happy It Hurts\u201d<\/em><\/strong>\u00a0<strong>\u00e8<\/strong>\u00a0<strong>il quindicesimo album in studio di Bryan Adams e contiene 12 brani di cui \u00e8 autore.\u00a0<\/strong>Arriva dopo il successo<strong>\u00a0<\/strong>di \u201cShine a Light\u201d (2019) che, ha debuttato al numero uno delle classifiche degli album nel marzo del 2019 e contiene l\u2019omonimo singolo con Ed Sheeran e un duetto con Jennifer Lopez.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>\u00c8 uscita su tutte le piattaforme streaming e download la title track dell\u2019album.\u00a0<em>\u201cSo Happy It Hurts\u201d<\/em>\u00a0\u00e8 un brano up tempo\u00a0<\/strong>con un ritornello arioso e ritmato che entra in testa, sostenuto da energici riff e pronto a farsi spazio nelle playlist!<\/p>\n<p style=\"font-weight: 400;\">Il singolo \u00e8 accompagnato dal\u00a0<strong>video<\/strong>\u00a0diretto da Adams stesso<strong>:<\/strong>\u00a0<a href=\"https:\/\/youtu.be\/d0caIWs0O9c\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/youtu.be\/d0caIWs0O9c&amp;source=gmail&amp;ust=1638274084530000&amp;usg=AOvVaw2W3G3ZlmBjoGXuxW3cCLE7\">https:\/\/youtu.be\/d0caIWs0O9c<\/a>.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">L&#8217;album sar\u00e0 disponibile su tutte le piattaforme digitali, oltre che in formato fisico, in versione CD standard, CD deluxe con copertina lenticolare + libro con copertina rigida e vinile, vinile a colori e un cofanetto in edizione limitata che include CD deluxe, vinile, libro rilegato e foto autografata.\u00a0<strong>Qui il pre-order\u00a0<a href=\"https:\/\/bryanadams.lnk.to\/SoHappyItHurtsAlbum\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/bryanadams.lnk.to\/SoHappyItHurtsAlbum&amp;source=gmail&amp;ust=1638274084530000&amp;usg=AOvVaw1WTnxRsbKmmN_BfJ3A1n_I\">https:\/\/bryanadams.lnk.to\/SoHappyItHurtsAlbum<\/a>.<\/strong><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Partir\u00e0 a gennaio 2022 il tour mondiale,\u00a0<\/strong>che arriva in Italia per D&#8217;Alessandro e Galli a febbraio!\u00a0<strong>L\u201911 febbraio al Palazzo dello Sport di Roma, il 12 febbraio al Mandela Forum di Firenze e il 14 febbraio alla Zoppas Arena di Conegliano\u00a0<\/strong>(TV). Informazioni e dettagli prevendite su\u00a0<a href=\"http:\/\/www.dalessandroegalli.com\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.dalessandroegalli.com&amp;source=gmail&amp;ust=1638274084530000&amp;usg=AOvVaw3YS-mbpXdVacdLiN_cGqWe\">www.dalessandroegalli.com<\/a><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">BRYAN ADAMS ha attraversato con la sua musica 4 decenni, durante i quali ha pubblicato\u00a0<strong>14 album in studio<\/strong>. Le performance di Bryan Adams sono indimenticabili grazie alla sua\u00a0<strong>straordinaria presenza sul palco e alla sua inconfondibile voce.<\/strong>\u00a0Il suo modo di scrivere canzoni gli \u00e8 valso numerosi premi e riconoscimenti: 3 Academy Award nomination, 5 Golden Globe nomination, 1 Grammy award, 1 American Music Award, vari Juno Awards. \u00c8 stato inserito nella Hollywood Walk of Fame. Ha ricevuto l\u2019Allan Waters Humanitarian Award per i suoi concerti di beneficenza e il Governor General\u2019s Performing Arts Award per il suo contributo di una vita alle arti in Canada.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Bryan Adams \u00e8 anche un fotografo professionista, scatta lui stesso tutte le copertine dei suoi album. Ha scattato il\u00a0<strong>48\u00b0<\/strong>\u00a0<strong>calendario Pirelli per il 2022<\/strong>. Nella sua carriera ha pubblicato vari libri fotografici con i suoi lavori, l\u2019ultimo \u00e8 Homeless, del 2019.<\/p>\n<p style=\"font-weight: 400;\">\n<p><strong>CONNECT WITH BRYAN ADAMS<\/strong><\/p>\n<p><u><a href=\"https:\/\/www.bryanadams.com\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.bryanadams.com\/&amp;source=gmail&amp;ust=1638274084530000&amp;usg=AOvVaw1MjPWaUWCI3ewnRyFFpuMd\">Official<\/a><\/u>\u00a0|\u00a0<u><a href=\"https:\/\/www.facebook.com\/bryanadamsofficial\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.facebook.com\/bryanadamsofficial&amp;source=gmail&amp;ust=1638274084530000&amp;usg=AOvVaw3nv7w7aYw_djr9CoIJnBEV\">Facebook<\/a><\/u>\u00a0|\u00a0<u><a href=\"https:\/\/twitter.com\/bryanadams\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/twitter.com\/bryanadams&amp;source=gmail&amp;ust=1638274084530000&amp;usg=AOvVaw085aJlmi_RZAwz0q3C0vOB\">Twitter\u00a0<\/a><\/u>|\u00a0<u><a href=\"https:\/\/www.instagram.com\/bryanadams\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.instagram.com\/bryanadams\/&amp;source=gmail&amp;ust=1638274084531000&amp;usg=AOvVaw2XnfOMxqf_VIlrm_rrVauV\">Instagram<\/a><\/u>\u00a0|\u00a0<u><a href=\"https:\/\/www.youtube.com\/channel\/UCxuYPUdTZHRZKVRZ1km1plw\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.youtube.com\/channel\/UCxuYPUdTZHRZKVRZ1km1plw&amp;source=gmail&amp;ust=1638274084531000&amp;usg=AOvVaw1XNg0w_69vldIAs7Swjh0L\">YouTube<\/a><\/u><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BRYAN ADAMS L\u201911 MARZO 2022 ESCE IL NUOVO ALBUM \u201cSO HAPPY IT HURTS\u201d \u00a0 L\u2019album \u00e8 ora in pre-order https:\/\/bryanadams.lnk.to\/SoHappyItHurtsAlbum \u00a0 A febbraio IN CONCERTO a ROMA, FIRENZE e CONEGLIANO<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2021\/11\/29\/bryan-adams-e-in-pre-order-il-nuovo-album-so-happy-it-hurts-bmg-che-esce-l11-marzo-2022-a-febbraio-2022-tre-date-in-italia\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":28451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28450"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=28450"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28450\/revisions"}],"predecessor-version":[{"id":28452,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28450\/revisions\/28452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/28451"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=28450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=28450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=28450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}