{"id":28580,"date":"2021-12-03T17:53:02","date_gmt":"2021-12-03T17:53:02","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=28580"},"modified":"2021-12-03T18:10:12","modified_gmt":"2021-12-03T18:10:12","slug":"ieri-a-ficarazzi-premi-agli-atleti-siciliani-per-i-risultati-conseguiti-nel-2020","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2021\/12\/03\/ieri-a-ficarazzi-premi-agli-atleti-siciliani-per-i-risultati-conseguiti-nel-2020\/","title":{"rendered":"Ieri a Ficarazzi premi agli atleti siciliani per i risultati conseguiti nel 2020."},"content":{"rendered":"<p><strong>\u00a0Stella d\u2019Argento a Onofrio Giannone per la sua lunga carriera al Coni<\/strong><\/p>\n<p>FICARAZZI \u2013 Presso la sala conferenze del Comitato regionale Sicilia della Lega Nazionale Dilettanti si \u00e8 svolta ieri la manifestazione del Coni &#8220;Stelle al merito dello Sport&#8221;. Nel corso della cerimonia, svoltasi alla presenza, tra gli altri, del presidente del Coni Sicilia, Sergio D\u2019Antoni, del presidente del CR Sicilia Sandro Morgana e del presidente della Fijlkam (Federazione italiana judo, lotta, karate, arti marziali), Salvatore Li Vigni, sono stati premiati gli atleti siciliani distintisi nelle varie discipline sportive. Tra i premiati Onofrio Giannone, che ha ricevuto la Stella d\u2019Argento grazie alla sua lunga carriera al Coni.<br \/>\n(Nella foto, da sinistra, Li Vigni, D\u2019Antoni e Giannone)<\/p>\n<p><strong>MICHELANGELO MILAZZO<\/strong><br \/>\n(TESSERA ORDINE NAZIONALE DEI GIORNALISTI N. 062777)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Stella d\u2019Argento a Onofrio Giannone per la sua lunga carriera al Coni FICARAZZI \u2013 Presso la sala conferenze del Comitato regionale Sicilia della Lega Nazionale Dilettanti si \u00e8 svolta ieri<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2021\/12\/03\/ieri-a-ficarazzi-premi-agli-atleti-siciliani-per-i-risultati-conseguiti-nel-2020\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":28588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28580"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=28580"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28580\/revisions"}],"predecessor-version":[{"id":28582,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28580\/revisions\/28582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/28588"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=28580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=28580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=28580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}