{"id":28865,"date":"2021-12-15T08:57:12","date_gmt":"2021-12-15T08:57:12","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=28865"},"modified":"2021-12-15T08:57:12","modified_gmt":"2021-12-15T08:57:12","slug":"la-giovane-cantante-alessia-pinto-presenta-il-suo-primo-inedito","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2021\/12\/15\/la-giovane-cantante-alessia-pinto-presenta-il-suo-primo-inedito\/","title":{"rendered":"La giovane cantante Alessia Pinto presenta il suo primo inedito"},"content":{"rendered":"<p><strong><em>Santa Teresa di Riva.<\/em><\/strong> La giovane cantante Alessia Pinto sar\u00e0 ospite di Melina Patan\u00e8 e degli amici dell&#8217;associazione \u201cIl paese di fronte al mare\u201d nella serata del Caff\u00e8 d\u2019arte.<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-medium wp-image-28866\" src=\"https:\/\/www.radioempire.it\/wp-content\/uploads\/2021\/12\/ALESSIA-PINTO-foto-1-200x300.jpeg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.radioempire.it\/wp-content\/uploads\/2021\/12\/ALESSIA-PINTO-foto-1-200x300.jpeg 200w, https:\/\/www.radioempire.it\/wp-content\/uploads\/2021\/12\/ALESSIA-PINTO-foto-1-682x1024.jpeg 682w, https:\/\/www.radioempire.it\/wp-content\/uploads\/2021\/12\/ALESSIA-PINTO-foto-1-768x1154.jpeg 768w, https:\/\/www.radioempire.it\/wp-content\/uploads\/2021\/12\/ALESSIA-PINTO-foto-1.jpeg 852w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>Durante l\u2019evento, previsto nel pomeriggio di venerd\u00ec 17 dicembre, presso il Palazzo della Cultura, la cantante presenter\u00e0 il suo primo inedito dal titolo \u201dSempre cos\u00ec\u201d, scritto insieme al Maestro Luca Bechelli, autore e musicista, dedicandolo interamente alla sorella, suo importante punto di riferimento e amica per la vita; l\u2019esibizione sar\u00e0 accompagnata da un videoclip realizzato e curato dai registi Gianfranco Stracuzzi e Fabrizio Sergi, girato interamente a S. Teresa di Riva nel periodo estivo.<\/p>\n<p>Alessia Pinto, diciassettenne di S. Teresa di Riva, studentessa del Liceo Classico di S. Teresa di Riva, fin da bambina ha mostrato una spiccata passione per la musica, e da parecchi anni studia canto ottenendo nel corso degli anni vari successi. \u00a0Nel settembre scorso ha presentato questo suo inedito nel contest-tv \u201cNext-Generation\u201d per giovani talenti presso il prestigioso \u201cGardaland Theatre\u201d, riscuotendo apprezzamento da parte dei giudici, mentre nel prossimo marzo lo presenter\u00e0 a Verona per l&#8217;evento \u201cGiulietta Loves Romeo\u201d,\u00a0 selezionato dal Maestro Angelo Valsiglio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santa Teresa di Riva. La giovane cantante Alessia Pinto sar\u00e0 ospite di Melina Patan\u00e8 e degli amici dell&#8217;associazione \u201cIl paese di fronte al mare\u201d nella serata del Caff\u00e8 d\u2019arte. Durante<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2021\/12\/15\/la-giovane-cantante-alessia-pinto-presenta-il-suo-primo-inedito\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":28868,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28865"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=28865"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28865\/revisions"}],"predecessor-version":[{"id":28869,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/28865\/revisions\/28869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/28868"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=28865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=28865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=28865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}