{"id":29176,"date":"2021-12-29T14:38:36","date_gmt":"2021-12-29T14:38:36","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=29176"},"modified":"2021-12-29T14:38:36","modified_gmt":"2021-12-29T14:38:36","slug":"gaia-salina","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2021\/12\/29\/gaia-salina\/","title":{"rendered":"Gaia &#8211; &#8220;Salina&#8221;"},"content":{"rendered":"<div><strong><u>DA VENERD\u00cc 7 GENNAIO IN RADIO<\/u><\/strong><strong><u><\/p>\n<p><\/u><\/strong><\/div>\n<div><strong>SALINA<\/strong><strong><\/p>\n<p><\/strong><\/div>\n<div><strong>IL NUOVO SINGOLO CONTENUTO NELL\u2019ALBUM\u00a0<em>ALMA<\/em><\/strong><strong><br \/>\n<\/strong><strong><\/p>\n<p><\/strong><\/div>\n<p>\u00c8\u00a0<strong><em>Salina\u00a0<\/em><\/strong>il nuovo singolo di\u00a0<strong>GAIA<\/strong>, in radio da\u00a0<strong>venerd\u00ec 7 gennaio 2022<\/strong>. Il brano \u00e8 contenuto nel suo nuovo progetto discografico\u00a0<strong><em>ALMA<\/em><\/strong>\u00a0(Sony Music Italy\/Columbia Records), il secondo disco di inediti della cantautrice italo brasiliana che racchiude tutte le sue anime musicali e i suoi mondi.<\/p>\n<p><strong><em>Salina<\/em><\/strong>\u00a0\u00e8 famiglia, rifugio, magia. \u00c9 il ricordo della propria infanzia in un piccolo paese nel mantovano, Salina, dove il nonno di Gaia ha costruito una casa che potesse tenere unita tutta la famiglia, un luogo di aggregazione e di legami dove poter stare insieme. Il senso di appartenenza riporta l\u2019artista al dualismo dei suoi mondi e delle sue matrici culturali: \u201cl\u2019equatore da qua fa una linea che va dal Brasile ai campi di grano\u201d. Con questo brano il richiamo al ritornare al nido che ti crei e che ti hanno creato \u00e8 enfatizzato dal tema familiare, degli affetti che l\u2019hanno accerchiata di amore e che riescono a donare forza e al contempo ferire come nessun altro. Nel ritornello compaiono entrambe le lingue madri di Gaia, portando cos\u00ec un messaggio alla propria famiglia e a chi l\u2019ha cresciuta includendo tutte le sfaccettatura della sua multiculturalit\u00e0.<\/p>\n<p>Per la prima volta su un palco internazionale,\u00a0<strong>GAIA<\/strong>\u00a0si \u00e8 esibita al\u00a0<strong>Corona Capital 2021<\/strong>\u00a0durante la serata del\u00a0<strong>21 novembre<\/strong>\u00a0insieme a\u00a0<strong>Tame Impala<\/strong>,\u00a0<strong>Twenty One Pilots<\/strong>,\u00a0<strong>The<\/strong>\u00a0<strong>Kooks<\/strong>\u00a0e molti altri artisti che hanno partecipato a quello che viene definito uno dei festival pi\u00f9 importanti e all\u2019avanguardia dell\u2019America Latina.<\/p>\n<p>A gennaio partir\u00e0 il primo tour indoor di\u00a0<strong>GAIA<\/strong>\u00a0&#8211;\u00a0<strong><em>ALMA TOUR<\/em><\/strong>, prodotto da\u00a0<strong>Vivo Concerti<\/strong>, con la sua prima data a\u00a0<strong>Torino @ Hiroshima Mon Amour.\u00a0<\/strong>Con le prime date nei club\u00a0<strong>GAIA<\/strong>\u00a0\u00e8 pronta a creare una nuova personale dimensione on-stage presentando il suo universo artistico in atmosfere inedite che diventeranno sfondo del racconto delle sue anime musicali. Dopo la prima data il\u00a0<strong>24 gennaio<\/strong>\u00a0a\u00a0<strong>Torino<\/strong>, i live proseguiranno\u00a0<strong>mercoled\u00ec 26 gennaio\u00a0<\/strong>al<strong>\u00a0Viper<\/strong>\u00a0<strong>Theatre<\/strong>\u00a0di\u00a0<strong>Firenze<\/strong>,\u00a0<strong>gioved\u00ec 27<\/strong>\u00a0al\u00a0<strong>Duel Beat\u00a0<\/strong>di<strong>\u00a0Pozzuoli (NA)<\/strong>\u00a0e a seguire\u00a0<strong>GAIA\u00a0<\/strong>si esibir\u00e0\u00a0<strong>domenica 30 gennaio\u00a0<\/strong>al\u00a0<strong>Fabrique<\/strong>\u00a0di\u00a0<strong>Milano.\u00a0<\/strong>Il tour si concluder\u00e0 con la data di<strong>\u00a0gioved\u00ec 3 febbraio 2022\u00a0<\/strong>all\u2019<strong>Atlantico<\/strong>\u00a0<strong>Live<\/strong>\u00a0di\u00a0<strong>Roma<\/strong>. Biglietti disponibili su\u00a0<a href=\"https:\/\/panel2.mediasender.it\/api\/?class=client&amp;method=tl&amp;o=postcard&amp;u=ZXQ3bFF4cHV3NjhXNHg3c1hZdHdrVWg1Qld3S0JoSGwxTEdaYXc9PQ==&amp;c=WmQzbUhWWW9tcmNDKzE3NVVZOXJtd2wwQ1dRPQ==&amp;mq=b64e75a38fd2c718c1c3d77fae51e263\">www.vivoconcerti.com<\/a>\u00a0e presso tutte le rivendite autorizzate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DA VENERD\u00cc 7 GENNAIO IN RADIO SALINA IL NUOVO SINGOLO CONTENUTO NELL\u2019ALBUM\u00a0ALMA \u00c8\u00a0Salina\u00a0il nuovo singolo di\u00a0GAIA, in radio da\u00a0venerd\u00ec 7 gennaio 2022. Il brano \u00e8 contenuto nel suo nuovo progetto<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2021\/12\/29\/gaia-salina\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":29177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29176"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=29176"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29176\/revisions"}],"predecessor-version":[{"id":29178,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29176\/revisions\/29178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/29177"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=29176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=29176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=29176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}