{"id":29629,"date":"2022-01-17T10:44:27","date_gmt":"2022-01-17T10:44:27","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=29629"},"modified":"2022-01-17T10:44:27","modified_gmt":"2022-01-17T10:44:27","slug":"gino-astorina-rivisita-in-chiave-moderna-leredita-dello-zio-canonico-lo-spettacolo-in-scena-da-martedi-a-domenica-al-teatro-musco","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2022\/01\/17\/gino-astorina-rivisita-in-chiave-moderna-leredita-dello-zio-canonico-lo-spettacolo-in-scena-da-martedi-a-domenica-al-teatro-musco\/","title":{"rendered":"Gino Astorina rivisita in chiave moderna &#8220;L&#8217;eredit\u00e0 dello zio canonico&#8221;. Lo spettacolo in scena da marted\u00ec a domenica al Teatro Musco."},"content":{"rendered":"<p>Dopo Giuseppe Castiglia e il \u201csuo\u201d \u201cSan Giovanni Decollato\u201d, un altro big della comicit\u00e0 catanese sar\u00e0 protagonista al Teatro Angelo Musco. Toccher\u00e0 a Gino Astorina confrontarsi con un classico della tradizione firmato da Antonino Russo Giusti, \u201cL\u2019eredit\u00e0 dello zio canonico\u201d. Il nuovo allestimento, in scena da marted\u00ec 18 a domenica 23 gennaio, \u00e8 stato rivisitato in chiave moderna dal regista Antonello Capodici. Lo spettacolo, prodotto da Progetto Teatrando, vedr\u00e0 sul palco anche Carmela Buffa Calleo, Elisa Franco, Turi Giordano, Plinio Milazzo, Francesca Agate, Alberto Abbadessa, Gianni Fontanarosa (in video), con la partecipazione di Luciano Messina. Le scene sono di Salvo Manciagli.<\/p>\n<p>Gino Astorina, insieme con i suoi \u201ccomplici\u201d di sempre, \u00e8 un perfetto Antonio Favazza del terzo millennio. La sua comicit\u00e0 naturale, spontanea, vissuta, insieme alla sua catanesit\u00e0 moderna, borghese, caustica ma bonaria e benevola, rappresenta la versione aggiornata di una scuola umoristica, trasversale e senza tempo. Che attraversa, sia tutta la vicenda di Catania degli ultimi decenni, sia la deriva pi\u00f9 generale del nostro Paese.<br \/>\n\u201cAnni di trasformazioni spesso pi\u00f9 apparenti che reali &#8211; spiega il regista Antonello Capodici &#8211; di paradossi pi\u00f9 affrescati che ritratti a fondo: come se un copione, appunto, senza tempo, venisse via via aggiornato, con gags vecchie ma affidate a maschere dell\u2019oggi. Astorina, ma anche il grande Luciano Messina e Plinio Milazzo e Francesca Agate, sono stati &#8211; e sono &#8211; maestri inarrivabili di questa operazione costante di riscrittura: lo testimoniano i successi e i consensi ottenuti sia da solisti sia da ensemble. Insieme al gruppo costante di attori in questa sezione dedicata alla tradizione del cartellone diretto da Francesca Ferro, cio\u00e8 Carmela Buffa Calleo, Elisa Franco, Turi Giordano e Alberto Abbadessa, danno vita ad una \u201cEredit\u00e0\u201d ambientata oggi: senza forzature contemporaneiste n\u00e9 svenevolezze ideologiche, ma semplice al limite del poetico\u201d.<\/p>\n<p>In questo adattamento de \u201cL\u2019eredit\u00e0 dello zio canonico\u201d si ride e ci si stupisce di come tante (troppe) cose non siano per niente mutate nei cent\u2019anni trascorsi dall\u2019idea geniale dell\u2019avvocato Russo Giusti, e dal mito di Angelo Musco.<\/p>\n<p>\u201cUtilizzando una metafora calcistica &#8211; aggiunge Gino Astorina &#8211; posso dire di essere veramente felice di appartenere ad una squadra affiatatissima e di avere un allenatore come Antonello Capodici. Che ci ha fatto riscoprire la bellezza di risalire sul palco, cos\u00ec come di un testo che \u00e8 considerato un vecchio classico, ma in realt\u00e0 pu\u00f2 essere recitato, rimesso a nuovo, facendolo \u201ccorrere&#8221; come se fosse un\u2019auto di ultima generazione\u201d.<\/p>\n<p>\u201cL\u2019eredit\u00e0 dello zio canonico\u201d andr\u00e0 in scena marted\u00ec 18 gennaio (ore 21), mercoled\u00ec 19 (ore 21), gioved\u00ec 20 (ore 21), venerd\u00ec 21 (ore 21), sabato 22 (ore 17.30 e ore 21), domenica 23 (ore 18). Per informazioni 333 7781632 &#8211; 095 538188 &#8211; 345 3993368. Orario botteghino presso Teatro ABC: da marted\u00ec a sabato 16:00\/20:00, gioved\u00ec anche 10:00\/13:00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo Giuseppe Castiglia e il \u201csuo\u201d \u201cSan Giovanni Decollato\u201d, un altro big della comicit\u00e0 catanese sar\u00e0 protagonista al Teatro Angelo Musco. Toccher\u00e0 a Gino Astorina confrontarsi con un classico della<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2022\/01\/17\/gino-astorina-rivisita-in-chiave-moderna-leredita-dello-zio-canonico-lo-spettacolo-in-scena-da-martedi-a-domenica-al-teatro-musco\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":29630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29629"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=29629"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29629\/revisions"}],"predecessor-version":[{"id":29631,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29629\/revisions\/29631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/29630"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=29629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=29629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=29629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}