{"id":29728,"date":"2022-01-21T14:11:45","date_gmt":"2022-01-21T14:11:45","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=29728"},"modified":"2022-01-21T14:11:45","modified_gmt":"2022-01-21T14:11:45","slug":"alla-tenuta-rasocolmo-di-messina-di-scena-il-grande-jazz","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2022\/01\/21\/alla-tenuta-rasocolmo-di-messina-di-scena-il-grande-jazz\/","title":{"rendered":"Alla tenuta Rasocolmo di Messina di scena il grande jazz."},"content":{"rendered":"<p style=\"font-weight: 400;\">TORNA DOPO ANNI DI ASSENZA IN CITTA\u2019 L\u2019APPUNTAMENTO CON IL GRANDE JAZZ. AL VIA IL 5 FEBBRAIO \u201cWINEHOUSE CONCERT JAZZ\u201d LA PRIMA RASSEGNA JAZZ IN CANTINA NELLO SPLENDIDO SCENARIO DELLA TENUTA RASOCOLMO A CAPO RASOCOLMO (ME). PROTAGONISTI ALCUNI TRA I PIU\u2019 GRANDI MUSICISTI DEL JAZZ ITALIANO.<\/p>\n<p style=\"font-weight: 400;\">Torna alla Tenuta Rasocolmo di Capo Rasocolmo, a Messina, l\u2019appuntamento con la grande musica. Protagonista a partire da sabato 5 febbraio la rassegna \u201cWinehouse Concert Jazz\u201d, un appuntamento con i pi\u00f9 grandi nomi del jazz italiano in una atmosfera magica, calda e accogliente, quella della cantina.<\/p>\n<p style=\"font-weight: 400;\">\u00a0Un grande ritorno per la citt\u00e0 di Messina che dopo anni ritrova una rassegna interamente dedicata agli amanti del genere che avranno la possibilit\u00e0 di ascoltare artisti del calibro di Rosalba Lazzarotto, Luciano Troja, Giancarlo Mazz\u00f9, Antonio Cicero, Alessandro Blanco, Carmelo Coglitore, Pino Delfino, Anita Vitale e Mauro Schiavone. Cinque gli appuntamenti in programma.<\/p>\n<p style=\"font-weight: 400;\">Si parte sabato 5 febbraio con il duo Antonio Cicero e Alessandro Blanco, reduci dall\u2019incisione del loro primo disco con Elisa Lorena, con \u201cIntorno a Piazzolla\u201d, il 26 sar\u00e0 la volta di Giancarlo Mazz\u00f9 e Luciano Troja, di ritorno dai concerti di\u00a0 New York, con \u201cTales about standards\u201d. A seguire il 12 marzo Rosalba Lazzarotto, jazz vocalist, e compositrice tra le pi\u00f9 apprezzate del panorama italiano, e Luciano Troja in \u201cMy favorite songs\u201d. Il 26 sar\u00e0 la volta del \u201cDuo semiserio\u201d del poliedrico saxofonista e clarinettista Carmelo Coglitore insieme al solido contrabbasso di Pino Delfino, mentre a chiudere la rassegna, il 9 aprile sar\u00e0 la straordinaria voce di Anita Vitale in duo con Mauro Schiavone.<\/p>\n<p style=\"font-weight: 400;\">Durante tutta la rassegna sar\u00e0 in esposizione presso la cantina la mostra \u201cPieces of Wall\u201d di Demetrio Scopelliti, a cura di Mariateresa Zagone. Venti tavole di piccolo formato, testimoni di un respiro e di una vita che quei muri hanno abitato.<\/p>\n<p style=\"font-weight: 400;\">Per info \u00e8 possibile chiamare il numero 3933343760. I biglietti e gli abbonamenti saranno venduti esclusivamente sul sito\u00a0<a href=\"http:\/\/www.tenutarasocolmo.com\/eventi\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.tenutarasocolmo.com\/eventi&amp;source=gmail&amp;ust=1642850694458000&amp;usg=AOvVaw1sCCQ5IEdYzRX1BdOJ2C2v\">www.tenutarasocolmo.com\/eventi<\/a>.<\/p>\n<p style=\"font-weight: 400;\">Per l&#8217;accesso agli spettacoli e alla degustazione \u00e8 obbligatorio essere in possesso, secondo la normativa vigente, di Green Pass. Gradito, ma non obbligatorio, l\u2019esito di un tampone negativo. Per quanti lo esibiranno un piccolo omaggio della cantina.<\/p>\n<p style=\"font-weight: 400;\">\u00a0I posti sono limitati, max 25 persone, e sino ad esaurimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORNA DOPO ANNI DI ASSENZA IN CITTA\u2019 L\u2019APPUNTAMENTO CON IL GRANDE JAZZ. AL VIA IL 5 FEBBRAIO \u201cWINEHOUSE CONCERT JAZZ\u201d LA PRIMA RASSEGNA JAZZ IN CANTINA NELLO SPLENDIDO SCENARIO DELLA<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2022\/01\/21\/alla-tenuta-rasocolmo-di-messina-di-scena-il-grande-jazz\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":29729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29728"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=29728"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29728\/revisions"}],"predecessor-version":[{"id":29730,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29728\/revisions\/29730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/29729"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=29728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=29728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=29728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}