{"id":29743,"date":"2022-01-21T16:10:51","date_gmt":"2022-01-21T16:10:51","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=29743"},"modified":"2022-01-21T16:16:03","modified_gmt":"2022-01-21T16:16:03","slug":"samuela-schiliro-da-oggi-su-youtube-santa-madre-dellumanita-il-video-del-nuovo-singolo-della-cantautrice-e-primo-con-la-label-azzurra-music","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2022\/01\/21\/samuela-schiliro-da-oggi-su-youtube-santa-madre-dellumanita-il-video-del-nuovo-singolo-della-cantautrice-e-primo-con-la-label-azzurra-music\/","title":{"rendered":"SAMUELA SCHILIRO \/\/ da oggi su YouTube SANTA MADRE DELL\u2019UMANIT\u00c0 il video del nuovo singolo della cantautrice e primo con la label Azzurra Music"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>DA OGGI SU YOUTUBE<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><em><u>\u201cSANTA MADRE DELL\u2019UMANIT\u00c0<\/u><\/em><\/strong><em><u>\u201d<\/u><\/em><\/p>\n<p style=\"font-weight: 400;\"><strong>IL VIDEO DEL NUOVO SINGOLO DELLA CANTAUTRICE<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>E PRIMO CON LA LABEL AZZURRA MUSIC<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><em><a href=\"https:\/\/youtu.be\/KBYaRo_JapQ\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/youtu.be\/KBYaRo_JapQ&amp;source=gmail&amp;ust=1642863784213000&amp;usg=AOvVaw2_78a0C9kVmbVRAEam-xFR\">https:\/\/youtu.be\/KBYaRo_JapQ<\/a><\/em><\/strong><\/p>\n<p style=\"font-weight: 400;\">Da oggi \u00e8 online su YouTube <strong><em>\u201cSanta Madre dell\u2019Umanit\u00e0\u201d\u00a0<\/em><\/strong>(Azzurra Music \/ Caf\u00e8 Concerto Italia), il video del nuovo singolo di\u00a0<strong>Samuela Schilir\u00f2<\/strong>, cantautrice di origini goriziane e siciliana d\u2019adozione. Nel brano, gi\u00e0 disponibile in streaming, in digital download e in rotazione radiofonica, l\u2019artista sperimenta sonorit\u00e0 differenti rispetto alle precedenti produzioni, attualizzando suoni retr\u00f2 anni \u201980 ai giorni nostri. In\u00a0<strong><em>\u201cSanta Madre dell\u2019Umanit\u00e0\u201d\u00a0<\/em><\/strong>miscela in modo giocoso i suoni classici delle chitarre elettriche, marchio distintivo del suo stile, alle drum machine e ai sintetizzatori.\u00a0L\u2019impianto ritmico, sempre estremamente importante e che vuole rappresentare il senso di ansia e frenesia che permea tutto il brano, diviene minimale per lasciare maggiore spazio all\u2019armonia.<\/p>\n<p style=\"font-weight: 400;\"><strong><em>Santa Madre dell\u2019Umanita\u2019 dove hai sbagliato pure tu<\/em><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><em>e torna in mente quel che mente sempre<\/em><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><em>trovami un sistema per fuggire da quest\u2019ansia esistenziale<\/em><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><em>che da sola non mi passa per niente<\/em><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><em>.<\/em><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Samuela Schilir\u00f2: \u201c<\/strong><em>Santa Madre dell\u2019Umanit\u00e0\u201d pu\u00f2 sembrare una bestemmia e in qualche modo lo \u00e8, o forse \u00e8 semplicemente una preghiera laica. \u00c8 la mia fotografia della realt\u00e0 di oggi: distorta frenetica accelerata confusa intrisa di spettacolare solitudine, in cui non si riesce pi\u00f9 a distinguere il reale dal virtuale, in cui l\u2019umanit\u00e0, nel senso letterale del termine, pare aver sbagliato qualcosa o essere destinata all\u2019estinzione. Tutto (il circo de) l\u2019orrore che ci circonda sembra passare inosservato o non toccarci minimamente e cos\u00ec quando c\u2019\u00e8 un uomo che non sa pi\u00f9 dove andare, tu ti giri e lasci fare. Un mondo fatto di pose, di giudizi, di razzismo medievale, di facili insulti e facili condanne, di menzogne rese verit\u00e0 assoluta, di paure disfunzionali, talmente contraddittori e paradossali da divenire un carnevale, in cui nessuno vede tocca e sente pi\u00f9 nessuno. In cui tutto \u00e8 velocissimo e facilmente dimenticabile, come le storie su Instagram che durano ventiquattro ore (tutto gi\u00e0 saputo gi\u00e0 vissuto in una storia, di cui niente poi ci resta e cancella la memoria) in cui \u00e8 necessario mostrarsi, magari inventandosi una vita al di l\u00e0 di uno schermo, per sentirsi davvero vivi. Si parla tanto di progresso e innovazione, ma a volte a me pare involuzione. In questo brano per\u00f2 non c\u2019\u00e8 solo la mia ansia esistenziale, che deriva da quanto ho descritto finora, ma anche il mio profondo desiderio di cambiamento, di autenticit\u00e0, della purezza dell\u2019essenza, di contatto fisico e di quella sana incoscienza puerile che pu\u00f2 salvare il mondo. Ed ecco perch\u00e9 invoco la santa madre dell\u2019umanit\u00e0, che a un certo punto deve essersi inceppata, perch\u00e9 torni a fare il suo lavoro. Se vogliamo attribuire tutto questo alla pandemia, facciamolo pure, ma io credo che quella sia stata e sia solo un amplificatore. L\u2019arguta penna di Mariagiovanna Lauretta, co-autrice del testo, ha condiviso con me questo punto di vista o sarebbe meglio dire questo punto di cuore. Per descrivere questa fotografia, ho utilizzato un tappeto sonoro che coniugasse le mie varie anime musicali. Mi piacciono le sfide e i cambiamenti e mi affascina la possibilit\u00e0 di servirmi della modernit\u00e0 per raccontare la mia essenza un po\u2019 anziana e un po\u2019 bambina.<\/em><\/p>\n<p style=\"font-weight: 400;\"><strong><em>\u201cSanta Madre dell\u2019Umanit\u00e0\u201d<\/em><\/strong><em>\u00a0<\/em>\u00e8 stato composto da\u00a0<strong>Samuela Schilir\u00f2<\/strong>\u00a0che ne ha scritto anche il testo con\u00a0<strong>Mariagiovanna Lauretta<\/strong>. Produzione artistica:\u00a0<strong>Samuela Schilir\u00f2<\/strong>. Registrato da\u00a0<strong>Michele Musarra<\/strong>\u00a0presso il\u00a0<strong>Phantasma Recording Studio<\/strong>\u00a0di San Giovanni La Punta (CT). Mixato e masterizzato da\u00a0<strong>Paolo Lovat<\/strong>. Foto di\u00a0<strong>Rori Palazzo<\/strong>. Grafica di\u00a0<strong>Damiano Friggi<\/strong>. Make up di\u00a0<strong>Francesco Paolo Catalano<\/strong>. Hanno suonato:\u00a0<strong>Samuela Schilir\u00f2<\/strong>\u00a0(voce, cori, chitarra elettrica, synth, programmazioni),\u00a0<strong>Denis Marino<\/strong>\u00a0(chitarra elettrica),\u00a0<strong>Michele Musarra<\/strong>\u00a0(basso, programmazioni),\u00a0<strong>Mariagiovanna Lauretta<\/strong>\u00a0(piano),<strong>Vincenzo Di Silvestro<\/strong>\u00a0(violino).<\/p>\n<p style=\"font-weight: 400;\"><strong><em>\u201cSanta Madre dell\u2019Umanit\u00e0\u201d<\/em><\/strong>\u00a0il video: prodotto da\u00a0<strong>Azzurra Music<\/strong>;\u00a0regia e fotografia:\u00a0<strong>Giuseppe Consales<\/strong>; riprese editing e post produzione:\u00a0<strong>Giuseppe Torrisi<\/strong>; direttrice di produzione:\u00a0<strong>Mariagiovanna Lauretta<\/strong>; make-up artist:\u00a0<strong>Antonella Muzzetta<\/strong>;\u00a0 soggetto:\u00a0<strong>Giuseppe Consales<\/strong>,\u00a0<strong>Mariagiovanna Lauretta<\/strong>,<strong>\u00a0Samuela Schilir\u00f2<\/strong>.\u00a0Cast:\u00a0<strong>Fabio Arcidiacono<\/strong>,\u00a0<strong>Carla Calabrese<\/strong>,<strong>\u00a0Anna Consoli<\/strong>,<strong>\u00a0Alessandra Cosentino<\/strong>,<strong>\u00a0Domenico Costa\u00a0<em>The Putty<\/em><\/strong>,<strong>\u00a0Vincenzo Di Silvestro<\/strong>,<strong>\u00a0Marco Failla<\/strong>,<strong>\u00a0MoussaKouyate<\/strong>,\u00a0<strong>Filippo Pensavalle De Cristofaro<\/strong>,\u00a0<strong>Gabriele Platania<\/strong>,\u00a0<strong>Martina Rapisarda<\/strong>,\u00a0<strong>Cristiano Russo<\/strong><em>,<strong>\u00a0<\/strong><\/em><strong>Benedetta Sirianni<\/strong>,\u00a0<strong>Bruno Sirianni<\/strong>,<strong>\u00a0Martina Terrizzi<\/strong>. Si ringrazia:\u00a0<strong>Giuseppe\u00a0<\/strong>e<strong>\u00a0Ruggero Platania<\/strong>,\u00a0<strong>Dimitri Di Noto<\/strong>,\u00a0<strong>Gianfranco Di Giunta<\/strong>,\u00a0<strong>Carla Calabrese<\/strong>,\u00a0<strong>Valeria Orchidea Marzaduri<\/strong>,\u00a0<strong>Gabriele Platania<\/strong>,\u00a0<strong>la famiglia Sirianni<\/strong>,\u00a0<strong>Costumi\u00a0<em>Victor Victoria<\/em>\u00a0\u2013 Catania<\/strong>,\u00a0<strong>Digital Print\u00a0<em>Tu stampucca nocca<\/em>\u00a0\u2013 Catania<\/strong>.<\/p>\n<p style=\"font-weight: 400;\"><em>\u00a0<\/em><\/p>\n<p style=\"font-weight: 400;\"><strong>Samuela Schilir\u00f2<\/strong><\/p>\n<p style=\"font-weight: 400;\">Cantante chitarrista compositrice autrice produttrice. Goriziana trapiantata a Milano e poi a Catania. Nelle sue vene scorre sangue siciliano. &#8220;Da dove vieni?&#8221; \u00e8 una domanda che pu\u00f2 provocarle una crisi di identit\u00e0. Manifesta fin da piccolissima una particolare attitudine alla musica e alla chitarra, organizzando piccoli show in casa davanti a un pubblico di parenti selezionati e appositamente invitati. A undici anni si iscrive all&#8217;Istituto di Musica di Gorizia, in cui studia chitarra classica, teoria musicale e canto corale.\u00a0Dopo tre anni abbandona per cercare da s\u00e9 le emozioni sulla sua sei corde e dedicarsi allo studio della chitarra moderna (folk ed elettrica).\u00a0Seguono, quindi, le sue prime band, con cui si esibisce in veste di cantante e chitarrista e le sue prime composizioni che iniziano a distanziarsi dal territorio classico per sfociare poi nel suo recente\u00a0<em>rock d\u2019autore<\/em>. Il 2010 la vede tra le quattro finaliste del Premio Janis Joplin, il 2011 come guest in diversi festival, tra cui il Lilith Festival, il Live on the Rock e il Nuvolari Libera Trib\u00f9 e protagonista di un mini tour nei club per presentare in anteprima il suo lavoro, accompagnata sul palco dalla sua band.\u00a0Nello stesso anno un suo brano, \u201cReality\u201d, viene inserito nella raccolta \u201cFemale do it better\u201d edita da Dcave\/M.E.I. Demo Rai Radio 1 le dedica una puntata, trasmettendo in anteprima alcuni brani presenti nel suo primo disco. Il 3 aprile 2012 esce per Viceversa Records\/Dcave\/Emi \u201cNon sono\u201d, il primo disco di Samuela Schilir\u00f2. La sua cover \u201cDomani \u00e8 un altro giorno\u201d viene giudicata tra i dieci rifacimenti migliori in Italia, da Life Gate Radio, che supporta il brano trasmettendolo. Il videoclip de \u201cNel mio giardino\u201d, secondo singolo estratto dall\u2019album, entra nei finalisti del P.I.V.I. 2012. \u201cNon sono\u201d riscuote numerosi successi sia tra la critica che tra il pubblico e tutto il 2012 e parte del 2013 vedono Samuela impegnata in un\u2019intensa attivit\u00e0 promozionale (show case in Feltrinelli, radio nazionali, Panorama unplugged ecc.) e live. Il suo tour attraversa i club, le piazze e i festival di tutta la penisola, portando Samuela a esibirsi anche sullo stesso palco di Nada, Marina Rei, Niccol\u00f2 Fabi, Mario Venuti, Cristina Don\u00e0, Motta, Colapesce, Dimartino, Mauro Ermanno Giovanardi, I Ministri, 24 Grana, Amor Fou, Criminal Jockers, Famelika. Nel 2014 intraprende il \u201cNon Sono SOLA Tour\u201d, in cui Samuela porta in giro per l\u2019Italia il proprio repertorio in chiave acustica, esibendosi da sola, accompagnata sul palco dalla sua fida chitarra e dal suo pedale stomp. Samuela si assenta dalle scene per quasi tre anni, periodo in cui comunque continua la sua attivit\u00e0 di ricerca, studio e scrittura musicale. Nel 2013 incontra Nica Midulla Le Pira, fondatrice della Waterbirds e madre del compianto Francesco Virlinzi, scopritore e produttore di molti artisti italiani, fra i quali Carmen Consoli, Mario Venuti, Moltheni e Flor de Mal. Nica produrr\u00e0 il suo secondo album \u201cC\u2019\u00e8 sempre un motivo\u201d, che vede la produzione artistica della stessa cantautrice e la collaborazione di nomi di rilievo della discografia italiana: il maestro Denis Marino (Carmen Consoli, Nada, Luca Madonia e Toni Carbone dei Denovo, Gabriella Lucia Grasso, Malmaritate e molti altri) in qualit\u00e0 di co-arrangiatore del disco, assieme a Samuela; Riccardo Parravicini (Niccol\u00f2 Fabi, Daniele Silvestri, Max Gazz\u00e8, Marlene Kuntz) per il missaggio e Giovanni Versari (Muse, Irene Grandi, Fabi Silvestri Gazz\u00e8, Il Teatro degli Orrori) per il mastering. Nel disco \u00e8 presente anche un featuring con Burhanuddin Herrmann, molto caro a Samuela. Il risultato di questa pausa \u00e8 \u201cC\u2019\u00e8 sempre un motivo\u201d, uscito il 25 marzo 2016 per Waterbirds\/Believe Digital e anticipato dal singolo \u201cNiente che non sia tutto\u201d, in rotazione dal 15 gennaio 2016. Nel 2016 Samuela \u00e8 impegnata in un&#8217;intensa attivit\u00e0 promozionale e soprattutto live, che la vede calcare i palchi di tutta Italia con il suo \u201cC&#8217;\u00e8 sempre un motivo TOUR\u201d. Nello stesso anno entra fra i settanta finalisti di \u201cArea Sanremo 2016\u201d e tra i dodici del \u201cPremio De Andr\u00e8 2016\u201d, all&#8217;interno della cui finale si esibisce all&#8217;Auditorium Parco della Musica di Roma. Nello stesso mese viene notata da Red Ronnie che la ospita nella trasmissione \u201cOptima Red Alert\u201d. Il 27 febbraio 2017 apre il concerto di Niccol\u00f2 Fabi al Teatro Metropolitan di Catania e il 21 e 22 luglio i concerti di Sarah Jane Morris, rispettivamente al Cortile Platamone di Catania e al Teatro Estate di Noto (SR). Il 15 dicembre 2018 si esibisce al Teatro di Avola (SR) all\u2019interno della rassegna \u201cEquilibri, tutti siamo diversi\u201d, insieme a Mauro Ermanno Giovanardi, Colapesce e Dimartino. Nel 2021, Samuela firma un contratto editoriale come autrice in esclusiva per Caf\u00e8 Concerto Music Publishing. Nello stesso anno firma un contratto discografico con Azzurra Music, per la quale uscir\u00e0 il suo terzo disco in studio, anticipato dal singolo \u201cSanta Madre dell\u2019Umanit\u00e0\u201d fuori il 14 gennaio 2022 e dal video ufficiale il 21 gennaio.<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Samuela Schilir\u00f2 su:<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><a href=\"https:\/\/www.facebook.com\/SamuelaSchiliroOfficial\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.facebook.com\/SamuelaSchiliroOfficial&amp;source=gmail&amp;ust=1642863784213000&amp;usg=AOvVaw0GbYwAfyWOkI3xgPklmYy2\">Facebook<\/a><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><a href=\"https:\/\/www.instagram.com\/samuela.schiliro\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.instagram.com\/samuela.schiliro&amp;source=gmail&amp;ust=1642863784213000&amp;usg=AOvVaw2sB8H6y8qNrL3yi0iJ6Wkq\">Instagram<\/a><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><a href=\"https:\/\/open.spotify.com\/artist\/5UtCrXtkLCjn3aSw1CTo6U?si=3fqVZdogTu-9uA8u-jaWiA\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/open.spotify.com\/artist\/5UtCrXtkLCjn3aSw1CTo6U?si%3D3fqVZdogTu-9uA8u-jaWiA&amp;source=gmail&amp;ust=1642863784213000&amp;usg=AOvVaw0a7kZVwo90-CMcxYLXKVFV\">Spotify<\/a><\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong><a href=\"https:\/\/www.youtube.com\/user\/samuelaschiliropage\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.youtube.com\/user\/samuelaschiliropage&amp;source=gmail&amp;ust=1642863784213000&amp;usg=AOvVaw1wK_kSR44sn-yh4I7Yp9lL\">YouTube<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Santa Madre dell&#039;Umanit\u00e0 di Samuela Schilir\u00f2 (Official Video)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/KBYaRo_JapQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DA OGGI SU YOUTUBE \u201cSANTA MADRE DELL\u2019UMANIT\u00c0\u201d IL VIDEO DEL NUOVO SINGOLO DELLA CANTAUTRICE E PRIMO CON LA LABEL AZZURRA MUSIC https:\/\/youtu.be\/KBYaRo_JapQ Da oggi \u00e8 online su YouTube \u201cSanta Madre<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2022\/01\/21\/samuela-schiliro-da-oggi-su-youtube-santa-madre-dellumanita-il-video-del-nuovo-singolo-della-cantautrice-e-primo-con-la-label-azzurra-music\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":29744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29743"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=29743"}],"version-history":[{"count":3,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29743\/revisions"}],"predecessor-version":[{"id":29753,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29743\/revisions\/29753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/29744"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=29743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=29743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=29743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}