{"id":29842,"date":"2022-01-26T15:08:23","date_gmt":"2022-01-26T15:08:23","guid":{"rendered":"https:\/\/www.radioempire.it\/?p=29842"},"modified":"2022-01-26T15:08:23","modified_gmt":"2022-01-26T15:08:23","slug":"baltimora-colore","status":"publish","type":"post","link":"https:\/\/www.radioempire.it\/index.php\/2022\/01\/26\/baltimora-colore\/","title":{"rendered":"BALTIMORA &#8211; &#8220;COLORE&#8221;"},"content":{"rendered":"<p><strong>Artista dalle sorprendenti doti canore, producer di talento, musicista, autore dalla scrittura profonda, vincitore di X Factor 2021: tutto questo a soli 20 anni.<\/strong><\/p>\n<p><strong>BALTIMORA, dopo aver emozionato il pubblico di tutta Italia, grazie alla sua sensibilit\u00e0 e alla potenza della sua voce, \u00e8 pronto a spiccare il volo e lo fa con il suo nuovo singolo \u201c<em>COLORE<\/em>\u201d<\/strong>\u00a0(Columbia Records Italy\/Sony Music Italy),<strong>\u00a0in arrivo venerd\u00ec 28 gennaio. Il brano, che anticipa l\u2019EP d\u2019esordio di prossima uscita, \u00e8 disponibile da oggi,\u00a0<\/strong>luned\u00ec 24 gennaio,<strong>\u00a0in pre-save e pre-add al link\u00a0<\/strong><a href=\"https:\/\/panel2.mediasender.it\/api\/?class=client&amp;method=tl&amp;o=postcard&amp;u=ZXQ3bFExTjd3L2NEOVZ6dVhaQndnRVk1Q21jVFhBeWttTDJiS0UxamtnPT0=&amp;c=THRubFFVOHZpK1lKNEVUcVI4Y3czVVYyQ24wUkh4ZTUxdkNZS2trL2d6ZmlLQXh2ZkF6M2dmbTdSbTR1M0JndQ==&amp;mq=87782786eaf98ddfe63829427e16c574\"><strong>https:\/\/baltimora.lnk.to\/colore<\/strong><\/a><strong>.<\/strong><\/p>\n<p><strong>\u201c<em>Colore<\/em>\u201d\u00a0<\/strong>&#8211; presentato durante le audizioni del programma in una versione piano e voce &#8211;<strong>\u00a0\u00e8 una ballad dalle liriche dirompenti che, raccontando di un inconsolabile dolore, colpiscono come un pugno nello stomaco. In \u201c<em>Colore<\/em>\u201d, realizzato dallo stesso BALTIMORA in coproduzione con Simone Privitera,\u00a0 l\u2019artista si confronta anche con un beat ritmato, che dimostra a pieno la sua versatilit\u00e0.<\/strong><\/p>\n<p><strong><em>\u201c\u2018Colore\u2019\u00a0<\/em><\/strong>&#8211; commenta<strong>\u00a0BALTIMORA<\/strong>\u00a0&#8211;\u00a0<strong><em>\u00e8 un brano a cui sono molto legato, l\u2019ho scritto una notte di tre anni fa dopo una delusione d\u2019amore ed \u00e8 rimasto nel cassetto insieme a tutti gli altri. Parla di come nonostante le cose vadano male si cerchi sempre di ritrovare direttamente o indirettamente l\u2019altro, la difficolt\u00e0 di lasciar andare. Ho sempre saputo che il brano avesse un ritornello molto forte, ma ho sempre avuto difficolt\u00e0 ad accostargli una produzione. Ora credo abbia raggiunto una bellissima forma\u201d.<\/em><\/strong><\/p>\n<p><strong>Il nuovo singolo arriva dopo \u201c<em>Altro<\/em>\u201d e \u201c<em>Baltimora<\/em>\u201d, brani originali che il cantautore ha presentato durante i Live di X Factor. Se\u00a0<\/strong>In\u00a0<strong><em>\u201cAltro\u201d<\/em><\/strong>\u00a0convivono sorprendente purezza, incisi rap e ritornelli spinti ed energici in cui la voce si rompe svelando migliaia di diverse sfumature, &#8220;<strong><em>Baltimora<\/em><\/strong>&#8221; \u00e8 stato finora il suo brano pi\u00f9 intimo e che lo rappresenta a tal punto da aver deciso di fare del titolo il suo nome d\u2019arte.<\/p>\n<p><strong>BALTIMORA \u00e8 inoltre pronto a esibirsi live con il \u201cBALTIMORA LIVE TOUR 2022\u201d, il suo primo tour, in partenza a marzo 2022.\u00a0<\/strong>Questi i tre appuntamenti confermati finora: il<strong>\u00a019 marzo\u00a0<\/strong>al\u00a0<strong>Mamamia\u00a0<\/strong>di\u00a0<strong>SENIGALLIA (AN),<\/strong>\u00a0il\u00a0<strong>23 marzo<\/strong>\u00a0a<strong>\u00a0MILANO\u00a0<\/strong>presso la<strong>\u00a0Santeria Toscana\u00a0<\/strong>e il<strong>\u00a027 marzo\u00a0<\/strong>a<strong>\u00a0ROMA\u00a0<\/strong>al<strong>\u00a0Largo Venue. Biglietti e info disponibili su\u00a0<\/strong><a href=\"https:\/\/panel2.mediasender.it\/api\/?class=client&amp;method=tl&amp;o=postcard&amp;u=ZXQ3bFF4cHV3NjhXNHg3c1hZdHdrVWg1Qld3S0JoSGwxTEda&amp;c=THRubFFVOHZpK1lXNDBlMFFwUnBuVVI0Q0dvZEFBeWltYjJiS1I0K2hDeS9KQTFrTFE9PQ==&amp;mq=87782786eaf98ddfe63829427e16c574\"><strong>www.vivoconcerti.com<\/strong><\/a><strong>.\u00a0<\/strong><\/p>\n<p>Edoardo Spinsante, in arte\u00a0<strong>BALTIMORA<\/strong>, nato nel 2001, nasce e cresce ad Ancona, prima di trasferirsi a Milano per dedicarsi agli studi di Produzione Audio e alla sua musica. Edoardo scrive, arrangia e produce i suoi brani da anni ma li ha sempre tenuti per s\u00e9 fino a quando entra in contatto con\u00a0<strong>Pezzi Dischi<\/strong>. Grazie a loro decide di mettersi in gioco e iniziare il percorso davanti ai 4 giudici della quindicesima edizione di\u00a0<strong>X Factor<\/strong>, dove, oltre alle cover, ha presentato i due inediti \u201c<strong><em>Altro<\/em><\/strong>\u201d e\u00a0 \u201c<strong><em>Baltimora<\/em><\/strong>\u201d<strong>,\u00a0<\/strong>che sono diventati i singoli che lo hanno portato alla vittoria al forum di Assago. Il nuovo singolo \u201c<strong><em>Colore<\/em><\/strong>\u201d anticipa l\u2019EP d\u2019esordio di prossima uscita.<\/p>\n<div><a href=\"https:\/\/panel2.mediasender.it\/api\/?class=client&amp;method=tl&amp;o=postcard&amp;u=ZXQ3bFExTjd3L2NXNDBlMFhaTnNoa1p3RkdnVlhCdWsydkdXSlU1bG5qV2lPUUppUEE9PQ==&amp;c=ZXQ3bFExTjd3L2NXNDBlMFhaTnNoa1p3RkdnVlhCdWsydkdXSlU1bG5qV2lPUUppUEE9PQ==&amp;mq=87782786eaf98ddfe63829427e16c574\">https:\/\/www.instagram.com\/baltimoraa\/<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Artista dalle sorprendenti doti canore, producer di talento, musicista, autore dalla scrittura profonda, vincitore di X Factor 2021: tutto questo a soli 20 anni. BALTIMORA, dopo aver emozionato il pubblico<\/p>\n<div><a class=\"permalink\" href=\"https:\/\/www.radioempire.it\/index.php\/2022\/01\/26\/baltimora-colore\/\">Read More&#8230;<\/a><\/div>\n","protected":false},"author":2,"featured_media":29843,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29842"}],"collection":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/comments?post=29842"}],"version-history":[{"count":1,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29842\/revisions"}],"predecessor-version":[{"id":29844,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/posts\/29842\/revisions\/29844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media\/29843"}],"wp:attachment":[{"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/media?parent=29842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/categories?post=29842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioempire.it\/index.php\/wp-json\/wp\/v2\/tags?post=29842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}